{"id":3,"count":6,"description":"","link":"https:\/\/karriere.dachdeckermeister-gaertner.de\/index.php\/tag\/stretching\/","name":"Stretching","slug":"stretching","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/karriere.dachdeckermeister-gaertner.de\/index.php\/wp-json\/wp\/v2\/tags\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karriere.dachdeckermeister-gaertner.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/karriere.dachdeckermeister-gaertner.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/karriere.dachdeckermeister-gaertner.de\/index.php\/wp-json\/wp\/v2\/posts?tags=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}